{"id":1816,"date":"2019-06-22T18:26:10","date_gmt":"2019-06-22T17:26:10","guid":{"rendered":"https:\/\/the7.io\/classic-landing\/?post_type=dt_portfolio&amp;p=1816"},"modified":"2019-06-22T18:26:10","modified_gmt":"2019-06-22T17:26:10","slug":"the7-gutenberg-business","status":"publish","type":"dt_portfolio","link":"https:\/\/heroesproject.eu\/ro\/project\/the7-gutenberg-business\/","title":{"rendered":"The7: Business (Gutenberg)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":1610,"comment_status":"open","ping_status":"closed","template":"","dt_portfolio_category":[24],"dt_portfolio_tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The7: Business (Gutenberg) - HEROES Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/heroesproject.eu\/ro\/de\/project\/the7-gutenberg-business\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The7: Business (Gutenberg) - HEROES Project\" \/>\n<meta property=\"og:url\" content=\"https:\/\/heroesproject.eu\/ro\/de\/project\/the7-gutenberg-business\/\" \/>\n<meta property=\"og:site_name\" content=\"HEROES Project\" \/>\n<meta property=\"og:image\" content=\"https:\/\/heroesproject.eu\/wp-content\/uploads\/2018\/12\/demo-gut.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/heroesproject.eu\/#website\",\"url\":\"http:\/\/heroesproject.eu\/\",\"name\":\"HEROES Project\",\"description\":\"Recruiting made easy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/heroesproject.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-gutenberg-business\/#primaryimage\",\"inLanguage\":\"ro-RO\",\"url\":\"https:\/\/heroesproject.eu\/wp-content\/uploads\/2018\/12\/demo-gut.jpg\",\"contentUrl\":\"https:\/\/heroesproject.eu\/wp-content\/uploads\/2018\/12\/demo-gut.jpg\",\"width\":750,\"height\":500},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-gutenberg-business\/#webpage\",\"url\":\"https:\/\/heroesproject.eu\/de\/project\/the7-gutenberg-business\/\",\"name\":\"The7: Business (Gutenberg) - HEROES Project\",\"isPartOf\":{\"@id\":\"http:\/\/heroesproject.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-gutenberg-business\/#primaryimage\"},\"datePublished\":\"2019-06-22T17:26:10+00:00\",\"dateModified\":\"2019-06-22T17:26:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-gutenberg-business\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/heroesproject.eu\/de\/project\/the7-gutenberg-business\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-gutenberg-business\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/heroesproject.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/heroesproject.eu\/project\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The7: Business (Gutenberg)\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/dt_portfolio\/1816"}],"collection":[{"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/comments?post=1816"}],"version-history":[{"count":0,"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/dt_portfolio\/1816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/media\/1610"}],"wp:attachment":[{"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/media?parent=1816"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/dt_portfolio_category?post=1816"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/heroesproject.eu\/ro\/wp-json\/wp\/v2\/dt_portfolio_tags?post=1816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}