{"id":1786,"date":"2019-06-20T17:21:10","date_gmt":"2019-06-20T16:21:10","guid":{"rendered":"https:\/\/the7.io\/classic-landing\/?post_type=dt_portfolio&amp;p=1786"},"modified":"2019-06-20T17:21:10","modified_gmt":"2019-06-20T16:21:10","slug":"the7-digital-agency","status":"publish","type":"dt_portfolio","link":"https:\/\/heroesproject.eu\/ch\/project\/the7-digital-agency\/","title":{"rendered":"The7: Digital Agency"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":1225,"comment_status":"open","ping_status":"closed","template":"","dt_portfolio_category":[24,28],"dt_portfolio_tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The7: Digital Agency - HEROES Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/heroesproject.eu\/ch\/de\/project\/the7-digital-agency\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The7: Digital Agency - HEROES Project\" \/>\n<meta property=\"og:url\" content=\"https:\/\/heroesproject.eu\/ch\/de\/project\/the7-digital-agency\/\" \/>\n<meta property=\"og:site_name\" content=\"HEROES Project\" \/>\n<meta property=\"og:image\" content=\"https:\/\/heroesproject.eu\/wp-content\/uploads\/2016\/11\/d-digital-agency-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/heroesproject.eu\/#website\",\"url\":\"http:\/\/heroesproject.eu\/\",\"name\":\"HEROES Project\",\"description\":\"Recruiting made easy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/heroesproject.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-CH\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-digital-agency\/#primaryimage\",\"inLanguage\":\"de-CH\",\"url\":\"https:\/\/heroesproject.eu\/wp-content\/uploads\/2016\/11\/d-digital-agency-1.jpg\",\"contentUrl\":\"https:\/\/heroesproject.eu\/wp-content\/uploads\/2016\/11\/d-digital-agency-1.jpg\",\"width\":750,\"height\":500},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-digital-agency\/#webpage\",\"url\":\"https:\/\/heroesproject.eu\/de\/project\/the7-digital-agency\/\",\"name\":\"The7: Digital Agency - HEROES Project\",\"isPartOf\":{\"@id\":\"http:\/\/heroesproject.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-digital-agency\/#primaryimage\"},\"datePublished\":\"2019-06-20T16:21:10+00:00\",\"dateModified\":\"2019-06-20T16:21:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-digital-agency\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/heroesproject.eu\/de\/project\/the7-digital-agency\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/heroesproject.eu\/de\/project\/the7-digital-agency\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/heroesproject.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/heroesproject.eu\/project\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The7: Digital Agency\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/dt_portfolio\/1786"}],"collection":[{"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/comments?post=1786"}],"version-history":[{"count":0,"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/dt_portfolio\/1786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/media\/1225"}],"wp:attachment":[{"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/media?parent=1786"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/dt_portfolio_category?post=1786"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/heroesproject.eu\/ch\/wp-json\/wp\/v2\/dt_portfolio_tags?post=1786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}